{"id":119219,"date":"2023-04-12T16:08:58","date_gmt":"2023-04-12T19:08:58","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/jennifer-garner-revela-por-que-os-filhos-nao-tem-redes-sociais\/"},"modified":"2023-04-12T16:08:58","modified_gmt":"2023-04-12T19:08:58","slug":"jennifer-garner-revela-por-que-os-filhos-nao-tem-redes-sociais","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/jennifer-garner-revela-por-que-os-filhos-nao-tem-redes-sociais\/","title":{"rendered":"Jennifer Garner revela por que os filhos n\u00e3o t\u00eam redes sociais"},"content":{"rendered":"<p>Muitas celebridades n\u00e3o se importam de expor os filhos nas redes sociais, contudo, este n\u00e3o \u00e9 o caso de Jennifer Garner.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A artista, de 50 anos, esteve no programa &#8216;Today&#8217; e revelou que desafiou os filhos a provarem que as redes sociais s\u00e3o ben\u00e9ficas.<\/p>\n<p>&#8220;Disse aos meus filhos, &#8216;mostrem-me artigos que provem que as redes sociais s\u00e3o boas para os adolescentes e depois podemos conversar sobre isso'&#8221;, disse Garner, referindo-se a Violet, de 18 anos, Seraphina Rose, de 14 anos, e Samuel, de 11, frutos do anterior casamento com Ben Affleck.\u00a0<\/p>\n<p>Garner disse que tamb\u00e9m desafiou os filhos a encontrar artigos cient\u00edficos que mostrassem o contr\u00e1rio.\u00a0<\/p>\n<p>Os resultados foram de tal forma positivos que o filho de Jennifer &#8220;agradeceu&#8221; por estar afastado do mundo online.<\/p>\n<p>E no futuro poder\u00e1 mudar de ideia? A artista de Hollywood afirmou que ainda &#8220;tem um caminho longo pela frente&#8221;, mas que logo ver\u00e1.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2008862\/jennifer-garner-revela-por-que-os-filhos-nao-tem-redes-sociais?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muitas celebridades n\u00e3o se importam de expor os filhos nas redes sociais, contudo, este n\u00e3o<\/p>\n","protected":false},"author":0,"featured_media":119220,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-119219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119219"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119220"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}