{"id":119202,"date":"2023-04-12T15:08:42","date_gmt":"2023-04-12T18:08:42","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/o-que-se-sabe-sobre-o-termino-de-taylor-swift-e-joe-alwyn\/"},"modified":"2023-04-12T15:08:42","modified_gmt":"2023-04-12T18:08:42","slug":"o-que-se-sabe-sobre-o-termino-de-taylor-swift-e-joe-alwyn","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/o-que-se-sabe-sobre-o-termino-de-taylor-swift-e-joe-alwyn\/","title":{"rendered":"O que se sabe sobre o t\u00e9rmino de Taylor Swift e Joe Alwyn"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O t\u00e9rmino de Taylor Swift e Joe Alwyn foi motivo de tristeza para os swifters no \u00faltimo s\u00e1bado (8), j\u00e1 que o casal estava em um relacionamento de seis anos. Desde ent\u00e3o, todos est\u00e3o em busca dos motivos para a separa\u00e7\u00e3o repentina.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Segundo a revista People, o casal estava indo em dire\u00e7\u00f5es separadas. A fonte afirmou que amigos pr\u00f3ximos n\u00e3o acreditavam que Taylor e Alwyn fossem se separar definitivamente, devido \u00e0 grande liga\u00e7\u00e3o que tinham.<\/p>\n<p>Entre as diferen\u00e7as, o ator teria tido dificuldades em lidar com a fama em grande propor\u00e7\u00e3o que a ex-namorada conquistou no per\u00edodo p\u00f3s-pandemia. Quando estavam isolados juntos, Alwyn colaborou com a produ\u00e7\u00e3o dos \u00e1lbuns &#8220;Folklore e Evermore&#8221;, e \u00e9 listado com o pseud\u00f4nimo William Bowery.<\/p>\n<p>Ainda segundo a revista, as diferen\u00e7as de personalidade entre os dois se tornaram dif\u00edceis de ignorar. Apesar dos anos de conviv\u00eancia, o casal teria crescido distante. O Entertainment Tonight (ET), primeiro a confirmar o t\u00e9rmino, diz que Alwyn \u00e9 mais introvertido, t\u00edmido e quieto.<\/p>\n<p>O portal Entertainment Tonight (ET) tamb\u00e9m exp\u00f4s que a decis\u00e3o partiu mais de Taylor do que de Alwyn. Segundo fonte, a cantora quer focar em sua carreira. Taylor est\u00e1 em turn\u00ea com a &#8220;The Eras Tour&#8221; e o an\u00fancio aconteceu durante uma pausa de 13 dias dos shows.<\/p>\n<p>Juntos desde 2016, Taylor e Alwyn mantiveram a rela\u00e7\u00e3o longe dos holofotes. Em entrevista ao The Wall Street Journal, o ator disse que n\u00e3o confirmaria os boatos de um suposto noivado sob qualquer circunst\u00e2ncia: &#8220;se a resposta fosse sim, eu n\u00e3o diria. Se a resposta fosse n\u00e3o, eu n\u00e3o diria tamb\u00e9m&#8221;.<\/p>\n<p>O sil\u00eancio do casal fez com que grande aten\u00e7\u00e3o fosse direcionada para cada ato dos dois. Uma semana antes do t\u00e9rmino, Taylor trocou uma das m\u00fasicas da setlist da &#8220;The Eras Tour&#8221; e os f\u00e3s perceberam a diferen\u00e7a entre as letras. &#8220;Invisible String&#8221;, que fala sobre almas g\u00eameas, foi substitu\u00edda por &#8220;The 1&#8221;, uma m\u00fasica sobre amores perdidos.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2008662\/o-que-se-sabe-sobre-o-termino-de-taylor-swift-e-joe-alwyn?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O t\u00e9rmino de Taylor Swift e Joe Alwyn foi motivo<\/p>\n","protected":false},"author":0,"featured_media":119203,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-119202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119202"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119203"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}