{"id":119164,"date":"2023-04-12T10:09:05","date_gmt":"2023-04-12T13:09:05","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/com-r-13-bi-em-debitos-light-pede-a-justica-suspensao-de-pagamentos\/"},"modified":"2023-04-12T10:09:05","modified_gmt":"2023-04-12T13:09:05","slug":"com-r-13-bi-em-debitos-light-pede-a-justica-suspensao-de-pagamentos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/com-r-13-bi-em-debitos-light-pede-a-justica-suspensao-de-pagamentos\/","title":{"rendered":"Com R$ 1,3 bi em d\u00e9bitos, Light pede \u00e0 Justi\u00e7a suspens\u00e3o de pagamentos"},"content":{"rendered":"<p>A Light, distribuidora de energia el\u00e9trica no Estado do Rio, acionou a Justi\u00e7a na noite de segunda-feira pedindo o congelamento de suas obriga\u00e7\u00f5es financeiras &#8211; pagamento de juros e do principal de suas d\u00edvidas. A empresa alegou &#8220;interesse p\u00fablico&#8221; e pediu a instaura\u00e7\u00e3o de procedimento de media\u00e7\u00e3o com os seus credores. No processo, que tramita em sigilo, a empresa pede a avalia\u00e7\u00e3o da a\u00e7\u00e3o cautelar em car\u00e1ter de urg\u00eancia.<\/p>\n<p>Nesta semana, a companhia teria de amortizar R$ 435 milh\u00f5es de deb\u00eantures que est\u00e3o vencendo. Em junho, ter\u00e1 mais R$ 300 milh\u00f5es a quitar. O valor total para os pr\u00f3ximos meses chega a R$ 1,3 bilh\u00e3o, apurou o Broadcast (sistema de not\u00edcias em tempo real do Grupo Estado).<\/p>\n<\/p>\n<p>A medida foi considerada in\u00e9dita por advogados especialistas no setor el\u00e9trico, por amoldar instrumentos previstos na lei de recupera\u00e7\u00e3o judicial, como a media\u00e7\u00e3o entre as partes, ao regramento espec\u00edfico do setor, que pro\u00edbe pedidos de recupera\u00e7\u00e3o judicial pelas concession\u00e1rias de distribui\u00e7\u00e3o de energia.<\/p>\n<\/p>\n<p>A Light se queixa do rebaixamento de sua nota de cr\u00e9dito, de roubos de fios e de liga\u00e7\u00f5es clandestinas, bem como do impacto de decis\u00e3o do Supremo Tribunal Federal (STF) que determina que o ICMS n\u00e3o pode compor a base de c\u00e1lculo do PIS e da Cofins, o chamado tema n.\u00ba 69 do STF &#8211; o que implica devolu\u00e7\u00e3o de cr\u00e9ditos aos clientes.<\/p>\n<\/p>\n<p>A companhia informou no processo que tenta uma &#8220;solu\u00e7\u00e3o consensual, por media\u00e7\u00e3o coletiva, de forma ison\u00f4mica com o grupo de credores financeiros&#8221;, o que a protegeria de &#8220;ataques prematuros e inesperados&#8221;. Para isso, disse a Light na a\u00e7\u00e3o cautelar, \u00e9 necess\u00e1ria uma reuni\u00e3o com &#8220;o polo passivo&#8221; (credores).<\/p>\n<\/p>\n<p>Segundo o presidente da Light, Octavio Lopes, o pedido feito \u00e0 Justi\u00e7a ocorreu ap\u00f3s a realiza\u00e7\u00e3o de &#8220;mais de 40 reuni\u00f5es&#8221; com os credores sem haver um acordo (mais informa\u00e7\u00f5es nesta p\u00e1gina).<\/p>\n<\/p>\n<p><b>Pedidos<\/b><\/p>\n<\/p>\n<p>O pedido de tutela de urg\u00eancia na a\u00e7\u00e3o busca que sejam suspensas as obriga\u00e7\u00f5es financeiras, ao menos at\u00e9 que se aguarde o julgamento de primeiro grau da a\u00e7\u00e3o da empresa. No processo, a concession\u00e1ria de energia el\u00e9trica disse que a suspens\u00e3o das obriga\u00e7\u00f5es com os credores financeiros se daria &#8220;enquanto n\u00e3o realizada a readequa\u00e7\u00e3o temporal de tais obriga\u00e7\u00f5es&#8221;, ou seja, enquanto a concession\u00e1ria tenta reequilibrar a sua contabilidade. <\/p>\n<\/p>\n<p>H\u00e1 poucos dias, a Light informou preju\u00edzo de R$ 5,5 bilh\u00f5es em 2022. O balan\u00e7o destacou as perdas da empresa com furtos e liga\u00e7\u00f5es clandestinas, sob o comando de mil\u00edcias atuantes no Estado do Rio, e apontou que a situa\u00e7\u00e3o &#8220;alheia \u00e0 sua vontade e inger\u00eancia&#8221; levou a preju\u00edzos de R$ 600 milh\u00f5es em 2021. &#8220;Neste mesmo ano, a fim de frear tal sangria, 30% dos investimentos feitos pela Light &#8211; mais de R$ 450 milh\u00f5es &#8211; foram destinados ao combate de tais il\u00edcitos&#8221;, escreveram os advogados da empresa.<\/p>\n<\/p>\n<p>O processo movido pela Light ressaltou a falta de seguran\u00e7a no Estado. &#8220;Engana-se quem, diante do quadro que o Rio de Janeiro enfrenta &#8211; devolu\u00e7\u00e3o de concess\u00f5es, por exemplo, com a depreda\u00e7\u00e3o do patrim\u00f4nio p\u00fablico pelo pr\u00f3prio usu\u00e1rio -, afirma que esta, al\u00e9m de tantos outros servi\u00e7os prestados por diversas concession\u00e1rias, n\u00e3o esteja passando por dificuldades&#8221;, afirmou a empresa na a\u00e7\u00e3o.<\/p>\n<\/p>\n<p><b>Quest\u00e3o tribut\u00e1ria<\/b><\/p>\n<\/p>\n<p>A concession\u00e1ria informou ainda que sofre com os impactos da Lei 14.385, de junho passado, que determinou a devolu\u00e7\u00e3o integral aos consumidores de cr\u00e9ditos tribut\u00e1rios conquistados ap\u00f3s a exclus\u00e3o do ICMS da base de c\u00e1lculo do PIS e da Cofins nas contas de luz de forma retroativa. <\/p>\n<\/p>\n<p>A legisla\u00e7\u00e3o \u00e9 amparada em julgamento de um recurso extraordin\u00e1rio pela ministra do Supremo C\u00e1rmen L\u00facia. A decis\u00e3o criou o chamado tema n.\u00ba 69 de repercuss\u00e3o geral do STF e define as regras sobre a incid\u00eancia do ICMS no c\u00e1lculo do PIS e da Cofins.<\/p>\n<\/p>\n<p>Logo ap\u00f3s a decis\u00e3o de C\u00e1rmen L\u00facia, em maio de 2021, a companhia come\u00e7ou a devolver os cr\u00e9ditos: R$ 374,2 milh\u00f5es, no reajuste de 2021, e R$ 1,05 bilh\u00e3o no reajuste de 2022. Ao fim de dezembro de 2022, houve revis\u00e3o tarif\u00e1ria extraordin\u00e1ria negativa de 5,89% decorrente da devolu\u00e7\u00e3o. Para 2023, h\u00e1, em tese, montante expressivo a ser ressarcido aos clientes por meio de desconto nas tarifas.<\/p>\n<\/p>\n<p>Ainda no pedido, a Light citou &#8220;desafios&#8221;, entre furtos e liga\u00e7\u00f5es clandestinas, al\u00e9m da rela\u00e7\u00e3o desses crimes com as mil\u00edcias que atuam no Estado. Afirmou ainda que &#8220;a energia furtada nos 36 munic\u00edpios atendidos pelo Grupo Light no Rio de Janeiro seria suficiente para abastecer, por quatro anos, a cidade de Nova Igua\u00e7u, que tem mais de 820 mil habitantes&#8221;.<\/p>\n<\/p>\n<p>A Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) informou que o pedido de medida cautelar da Light a respeito de suas obriga\u00e7\u00f5es financeiras n\u00e3o teve impacto sobre as chamadas &#8220;obriga\u00e7\u00f5es intrassetoriais&#8221;.<\/p>\n<\/p>\n<p>&#8220;Nenhuma obriga\u00e7\u00e3o intrassetorial teve seus pagamentos suspensos ou postergados, o que inclui contratos da distribuidora com geradores, transmissores e o pagamento dos encargos setoriais. Tamb\u00e9m est\u00e3o preservadas integralmente as obriga\u00e7\u00f5es com fornecedores de servi\u00e7os, equipamentos, m\u00e3o de obra e funcion\u00e1rios&#8221;, declarou a ag\u00eancia, em nota.  <\/p>\n<\/p>\n<p><b>Sem processo, acordo seria &#8216;imposs\u00edvel&#8217;, diz presidente da empresa<\/b><\/p>\n<\/p>\n<p>O presidente do Grupo Light, Octavio Lopes, afirmou que a a\u00e7\u00e3o na Justi\u00e7a se justifica porque &#8220;seria praticamente imposs\u00edvel&#8221; obter acordos com os credores dentro de um &#8220;prazo razo\u00e1vel&#8221;, de tr\u00eas a seis meses. &#8220;Ficou claro para a gente nas \u00faltimas duas semanas que n\u00e3o conseguir\u00edamos 100% da via extrajudicial&#8221;, disse Lopes, em entrevista ao <i>Broadcast<\/i>.<\/p>\n<\/p>\n<p>Ele afirmou que, embora houvesse conversas preliminares com os credores, as negocia\u00e7\u00f5es s\u00f3 foram intensificadas ap\u00f3s a divulga\u00e7\u00e3o do balan\u00e7o no quarto trimestre de 2022 da empresa, no fim de mar\u00e7o, tendo em vista que a d\u00edvida da companhia est\u00e1 pulverizada entre detentores de deb\u00eantures e de bonds &#8211; que precisavam de &#8220;equidade de informa\u00e7\u00f5es&#8221;, fornecida a partir da publica\u00e7\u00e3o dos resultados.<\/p>\n<\/p>\n<p>Segundo Lopes, o processo ajuizado foi a &#8220;alternativa vi\u00e1vel&#8221; tamb\u00e9m tendo em vista o servi\u00e7o de d\u00edvida que a companhia tem previsto para a pr\u00f3xima segunda-feira. &#8220;Sentimos concord\u00e2ncia esmagadora dos credores com a nossa vis\u00e3o, que n\u00e3o poder\u00edamos usar mais os recursos do grupo, muito limitados e muito inferiores \u00e0s necessidades de caixa da companhia nos pr\u00f3ximos dois anos, para fazer solu\u00e7\u00f5es paliativas&#8221;, disse o presidente do grupo. Ele comparou a Light a empresas de outros setores que pedem recupera\u00e7\u00e3o judicial. &#8220;Essas empresas t\u00eam fornecedor atrasado, atrasam impostos, a gente n\u00e3o tem nada disso.&#8221; <\/p>\n<\/p>\n<p> As informa\u00e7\u00f5es s\u00e3o do jornal <b>O Estado de S. Paulo.<\/b><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2008768\/com-r-1-3-bi-em-debitos-light-pede-a-justica-suspensao-de-pagamentos?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Light, distribuidora de energia el\u00e9trica no Estado do Rio, acionou a Justi\u00e7a na noite<\/p>\n","protected":false},"author":0,"featured_media":119165,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-119164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119164"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119165"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}