{"id":119116,"date":"2023-04-12T06:38:47","date_gmt":"2023-04-12T09:38:47","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=119116"},"modified":"2023-04-12T06:38:48","modified_gmt":"2023-04-12T09:38:48","slug":"via-brasil-br-163-programacao-semanal-de-obras-na-br-163-e-br-230-7","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/via-brasil-br-163-programacao-semanal-de-obras-na-br-163-e-br-230-7\/","title":{"rendered":"Via Brasil BR-163 &#8211; Programa\u00e7\u00e3o Semanal de Obras na BR-163 e BR-230"},"content":{"rendered":"\n<p>A Via Brasil BR-163, empresa do grupo Conasa, informa a programa\u00e7\u00e3o semanal de obras de melhoria de asfalto no trecho da BR-163, entre Sinop (MT) e os acessos aos portos, em Miritituba (PA). A programa\u00e7\u00e3o busca oferecer maior previsibilidade \u00e0s viagens dos usu\u00e1rios.<br><br><strong>BR-163 no Mato Grosso:<\/strong><\/p>\n\n\n\n<p>Entre Sinop e a divisa MT\/PA (km 855 ao km 1.115)<\/p>\n\n\n\n<p><br><strong>BR-163 no Par\u00e1:<\/strong><br><br>Entre a divisa MT\/PA a Alvorada da Amaz\u00f4nia (km 33 a km 260)<br>De Santa J\u00falia a Campo Verde (km 350 a km 674)<\/p>\n\n\n\n<p><strong>BR-230 no Par\u00e1:<\/strong><br><br>De Campo Verde a Miritituba (km 1.100 a km 1.124)<br><br>Para execu\u00e7\u00e3o das obras com seguran\u00e7a e no menor tempo poss\u00edvel, \u00e9 necess\u00e1rio ado\u00e7\u00e3o do sistema pare-e-siga, pelo qual o tr\u00e1fego \u00e9 liberado de tempos em tempos, uma vez por sentido. Assim, \u00e9 importante que os usu\u00e1rios programem suas viagens e saiam com mais anteced\u00eancia. Tamb\u00e9m \u00e9 fundamental respeitar a sinaliza\u00e7\u00e3o de obras e as instru\u00e7\u00f5es dos operadores do pare-e-siga.<br><br>A concession\u00e1ria ressalta que tem se esfor\u00e7ado para reduzir ao m\u00e1ximo os reflexos sobre os motoristas. O modelo de trabalho adotado visa garantir mais agilidade, maior produtividade e seguran\u00e7a tanto aos usu\u00e1rios quanto aos colaboradores que atuam nas obras.<\/p>\n\n\n\n<p>Importante:<\/p>\n\n\n\n<p>A Via Brasil BR-163 e a ANTT est\u00e3o em campanha pela seguran\u00e7a nas estradas. Estamos fazendo nossa parte e cuidando para que a estrada esteja cada vez mais segura. Agora \u00e9 sua vez de fazer a sua parte. Como motorista ou pedestre, juntos salvamos vidas.<\/p>\n\n\n\n<p><strong><em><span class=\"has-inline-color has-vivid-cyan-blue-color\">Da Assessoria\/Foto: Acervo Via Brasil BR-163<\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Via Brasil BR-163, empresa do grupo Conasa, informa a programa\u00e7\u00e3o semanal de obras de<\/p>\n","protected":false},"author":2,"featured_media":119117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,37],"tags":[],"class_list":["post-119116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-regionais"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119116"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119116\/revisions"}],"predecessor-version":[{"id":119118,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119116\/revisions\/119118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119117"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}