{"id":119011,"date":"2023-04-11T16:08:19","date_gmt":"2023-04-11T19:08:19","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/11\/prefeito-deve-assinar-nesta-semana-autorizacao-para-armamento-da-guarda-civil-em-lucas-do-rio-verde\/"},"modified":"2023-04-11T16:08:19","modified_gmt":"2023-04-11T19:08:19","slug":"prefeito-deve-assinar-nesta-semana-autorizacao-para-armamento-da-guarda-civil-em-lucas-do-rio-verde","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/11\/prefeito-deve-assinar-nesta-semana-autorizacao-para-armamento-da-guarda-civil-em-lucas-do-rio-verde\/","title":{"rendered":"Prefeito deve assinar nesta semana autoriza\u00e7\u00e3o para armamento da Guarda Civil em Lucas do Rio Verde"},"content":{"rendered":"<p>O prefeito Miguel Vaz deve assinar, ainda nesta semana, o Acordo de Coopera\u00e7\u00e3o T\u00e9cnica (ACT) com a Pol\u00edcia Federal para o armamento da Guarda Civil Municipal. A partir da autoriza\u00e7\u00e3o, a GCM de Lucas do Rio Verde deve se tornar primeira de Mato Grosso com permiss\u00e3o da PF de atuar com porte de arma.\u00a0<\/p>\n<p>\u201cN\u00f3s estamos trabalhando h\u00e1 mais de dois anos no projeto de reestrutura\u00e7\u00e3o da Guarda Civil municipal. Nesta segunda-feira (10), recebemos a not\u00edcia de que foi aprovado e o ACT est\u00e1 pronto para assinatura. Essa autoriza\u00e7\u00e3o \u00e9 um importante passo para a seguran\u00e7a no nosso munic\u00edpio\u201d, disse o prefeito, atrav\u00e9s da assessoria.\u00a0<\/p>\n<p>Como parte do processo de armamento, os agentes da GCM passaram por capacita\u00e7\u00e3o, no \u00faltimo ano, em de Cotia (SP). Em 2021, a Gest\u00e3o Municipal iniciou, por meio da Procuradoria e secretarias de Seguran\u00e7a P\u00fablica e de Governo e Administra\u00e7\u00e3o, a reformula\u00e7\u00e3o do estatuto da guarda. \u201cPara isso, foram realizadas reuni\u00f5es com os atuais agentes para ouvir as demandas da categoria e apresentar a proposta de melhoria\u201d, informou a prefeitura. \u00a0<\/p>\n<p>Ap\u00f3s esse processo, a prefeitura elaborou um novo projeto de Lei Complementar estabelecendo a nova estrutura da institui\u00e7\u00e3o. \u201cConclu\u00eddas estas etapas, da reformula\u00e7\u00e3o do estatuto e armamento, a pr\u00f3xima fase \u00e9 o lan\u00e7amento do Concurso P\u00fablico para o setor, previsto j\u00e1 para os pr\u00f3ximos meses\u201d, concluiu a prefeitura, atrav\u00e9s da assessoria. \u00a0<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Miguel Vaz deve assinar, ainda nesta semana, o Acordo de Coopera\u00e7\u00e3o T\u00e9cnica (ACT)<\/p>\n","protected":false},"author":0,"featured_media":119012,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-119011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119011"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119012"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}