{"id":118971,"date":"2023-04-11T11:08:35","date_gmt":"2023-04-11T14:08:35","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/11\/noiva-troca-carros-de-luxo-por-retroescavadora-no-casamento-eis-o-motivo\/"},"modified":"2023-04-11T11:08:35","modified_gmt":"2023-04-11T14:08:35","slug":"noiva-troca-carros-de-luxo-por-retroescavadora-no-casamento-eis-o-motivo","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/11\/noiva-troca-carros-de-luxo-por-retroescavadora-no-casamento-eis-o-motivo\/","title":{"rendered":"Noiva troca carros de luxo por retroescavadora no casamento. Eis o motivo"},"content":{"rendered":"<p>Hellen Campos, de 21 anos e residente no Par\u00e1, deixou de lado as limusines, fuscas ou charretes no dia do seu casamento. Em vez disso, decidiu chegar ao altar de uma forma mais original: em uma retroescavadeira.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Conforme relatado pelo portal G1, o casamento ocorreu no domingo, 9 de abril, e a jovem quis prestar uma homenagem ao pai, que sempre trabalhou com esse tipo de ve\u00edculo.<\/p>\n<p>&#8220;Meu noivo ficou desesperado querendo sair da igreja para me ver chegar e n\u00e3o o deixaram sair. Todos os convidados sa\u00edram correndo para ver o que estava acontecendo l\u00e1 fora&#8221;, contou Hellen ao G1.<\/p>\n<p>&#8220;Quis fazer diferente, porque ningu\u00e9m pensa dessa forma. As pessoas s\u00f3 querem luxo e eu n\u00e3o penso assim. Al\u00e9m de poder homenagear o meu pai que me ensinou tudo o que eu sei, inclusive trabalhamos juntos, prestando servi\u00e7o com retroescavadeiras&#8221;, acrescentou.<\/p>\n<p>Em um v\u00eddeo dispon\u00edvel na galeria acima, \u00e9 poss\u00edvel ver todo o percurso da noiva, desde quando entra na p\u00e1 do ve\u00edculo &#8211; forrada com um pl\u00e1stico preto para n\u00e3o sujar o vestido &#8211; at\u00e9 a chegada \u00e0 igreja.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2008365\/eua-armas-de-fogo-ja-mataram-mais-de-11500-pessoas-este-ano\" target=\"_blank\" rel=\"noopener noreferrer\">EUA: Armas de fogo j\u00e1 mataram mais de 11.500 pessoas este ano<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/2008392\/noiva-troca-carros-de-luxo-por-retroescavadora-no-casamento-eis-o-motivo?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hellen Campos, de 21 anos e residente no Par\u00e1, deixou de lado as limusines, fuscas<\/p>\n","protected":false},"author":0,"featured_media":118972,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-118971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=118971"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/118972"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=118971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=118971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=118971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}