{"id":118940,"date":"2023-04-11T08:08:21","date_gmt":"2023-04-11T11:08:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/11\/pagamento-extra-de-r-50-para-adolescentes-e-gestantes-comeca-em-junho\/"},"modified":"2023-04-11T08:08:21","modified_gmt":"2023-04-11T11:08:21","slug":"pagamento-extra-de-r-50-para-adolescentes-e-gestantes-comeca-em-junho","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/11\/pagamento-extra-de-r-50-para-adolescentes-e-gestantes-comeca-em-junho\/","title":{"rendered":"Pagamento extra de R$ 50 para adolescentes e gestantes come\u00e7a em junho"},"content":{"rendered":"<p>Ap\u00f3s adicional mensal de R$ 150 por crian\u00e7a, Bolsa Fam\u00edlia ter\u00e1 Benef\u00edcio Vari\u00e1vel Familiar de R$ 50 em junho<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (MDS), respons\u00e1vel pelo Programa Bolsa Fam\u00edlia (PBF), confirmou que em junho ser\u00e1 adicionado um valor extra ao programa de transfer\u00eancia de renda. Trata-se do Benef\u00edcio Vari\u00e1vel Familiar, um pagamento de R$ 50 destinado a fam\u00edlias que tenham gestantes, crian\u00e7as de 7 anos ou mais, e menos de 12 anos, ou adolescentes com idades entre 12 anos e 18 anos incompletos.<\/p>\n<p>Essa medida se diferencia do Benef\u00edcio Primeira Inf\u00e2ncia, de R$ 150, que \u00e9 multiplicado pelo n\u00famero de crian\u00e7as da fam\u00edlia na faixa et\u00e1ria de zero a 7 anos incompletos. No caso do Benef\u00edcio Vari\u00e1vel, os R$ 50 ser\u00e3o pagos uma \u00fanica vez no m\u00eas para fam\u00edlias que tenham crian\u00e7as maiores, adolescentes e\/ou gestantes em sua composi\u00e7\u00e3o.<\/p>\n<p>Esses adicionais est\u00e3o previstos no artigo 7\u00ba, Se\u00e7\u00e3o III (Dos benef\u00edcios financeiros), da Medida Provis\u00f3ria n\u00ba 1.164, de 2 de mar\u00e7o de 2023, que instituiu o PBF, substituindo o Aux\u00edlio Brasil. O governo estima que o programa beneficiar\u00e1 21,8 milh\u00f5es de fam\u00edlias em situa\u00e7\u00e3o de pobreza.<\/p>\n<p>O MDS tem realizado esfor\u00e7os para identificar fraudes na concess\u00e3o dos aux\u00edlios, resultando na suspens\u00e3o e cancelamento de benef\u00edcios com cadastros irregulares. Os recursos liberados podem ser direcionados aos complementos do programa, conforme previsto na MP.<\/p>\n<p>As parcelas de abril do Bolsa Fam\u00edlia ter\u00e3o in\u00edcio no dia 14 de abril, seguindo o calend\u00e1rio de pagamento de acordo com o n\u00famero de identifica\u00e7\u00e3o social (NIS) das fam\u00edlias benefici\u00e1rias.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2008348\/pagamento-extra-de-r-50-para-adolescentes-e-gestantes-comeca-em-junho?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s adicional mensal de R$ 150 por crian\u00e7a, Bolsa Fam\u00edlia ter\u00e1 Benef\u00edcio Vari\u00e1vel Familiar de<\/p>\n","protected":false},"author":0,"featured_media":118941,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-118940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=118940"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/118941"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=118940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=118940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=118940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}