{"id":118775,"date":"2023-04-10T15:02:23","date_gmt":"2023-04-10T18:02:23","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=118775"},"modified":"2023-04-10T15:21:28","modified_gmt":"2023-04-10T18:21:28","slug":"mato-grosso-investimentos-em-moradia-saude-e-educacao-sao-destaques-no-estado","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/10\/mato-grosso-investimentos-em-moradia-saude-e-educacao-sao-destaques-no-estado\/","title":{"rendered":"Mato Grosso: investimentos em moradia, sa\u00fade e educa\u00e7\u00e3o s\u00e3o destaques no estado"},"content":{"rendered":"\n<p><em>Estado tem maior valor m\u00e9dio do Bolsa Fam\u00edlia no Centro-Oeste, reajuste de 38% na merenda escolar e 127 vagas reservadas no Mais M\u00e9dicos<\/em><\/p>\n\n\n\n<p>Para o estado de Mato Grosso, os investimentos federais realizados nos 100 primeiros dias do terceiro mandato do presidente Luiz In\u00e1cio Lula da Silva tiveram impacto no \u00e2mbito social. O estado teve o maior valor m\u00e9dio de benef\u00edcio do Bolsa Fam\u00edlia no Centro-Oeste e 258 mil fam\u00edlias foram assistidas em mar\u00e7o, m\u00eas que marcou a retomada do programa.<\/p>\n\n\n\n<p>Mato Grosso foi, tamb\u00e9m, um dos estados contemplados com entrega de unidades habitacionais na retomada do Minha Casa, Minha Vida, e recebeu investimentos na sa\u00fade, para a garantia de cirurgias eletivas, al\u00e9m de ter sido o segundo estado do Centro-Oeste com maior reajuste no valor do or\u00e7amento para o Programa Nacional de Alimenta\u00e7\u00e3o Escolar (PNAE).<\/p>\n\n\n\n<p><strong>Confira as principais a\u00e7\u00f5es no estado:BOLSA FAM\u00cdLIA &#8211; <\/strong>Dono do maior valor m\u00e9dio do benef\u00edcio do novo Bolsa Fam\u00edlia no Centro-Oeste, de R$ 695,54, um recorde na hist\u00f3ria do programa de transfer\u00eancia de <\/p>\n\n\n\n<p>renda do Governo Federal para o estado, o Mato Grosso teve 258 mil fam\u00edlias, de todos os 141 munic\u00edpios, contempladas com o programa em mar\u00e7o. Um total de R$ 179 milh\u00f5es em recursos federais foram transferidos ao Mato Grosso para o pagamento dos benef\u00edcios.<\/p>\n\n\n\n<p>Relan\u00e7ado com novidades, o Bolsa Fam\u00edlia, al\u00e9m de assegurar o repasse m\u00ednimo de R$ 600, trouxe como principal inova\u00e7\u00e3o o Benef\u00edcio Primeira Inf\u00e2ncia, que garante um adicional de R$ 150 a cada crian\u00e7a entre 0 e 6 anos na composi\u00e7\u00e3o familiar. Em Mato Grosso, 153 mil crian\u00e7as receberam o Benef\u00edcio Primeira Inf\u00e2ncia. Para isso foram reservados R$ 22,8 milh\u00f5es dos R$ 179 milh\u00f5es transferidos ao estado. A partir de junho, para cada dependente entre sete e 18 anos e gestantes na composi\u00e7\u00e3o familiar haver\u00e1 um adicional de R$ 50.<\/p>\n\n\n\n<p>Em mar\u00e7o, Cuiab\u00e1 foi o munic\u00edpio com maior n\u00famero de benefici\u00e1rios: 44.849 fam\u00edlias receberam uma m\u00e9dia de R$ 684,16, resultado de um investimento de R$ 30 milh\u00f5es na capital matogrossense. Outros quatro munic\u00edpios tiveram mais de 6,5 mil benefici\u00e1rios: V\u00e1rzea Grande (32.627), Rondon\u00f3polis (16.430), C\u00e1ceres (9.853) e Barra do Gar\u00e7as (6.991).<\/p>\n\n\n\n<p><strong>SA\u00daDE &#8211; <\/strong>No campo da sa\u00fade, um repasse federal de R$ 18 milh\u00f5es foi destinado a hospitais, associa\u00e7\u00f5es, cl\u00ednicas, centro de preven\u00e7\u00e3o, casas de sa\u00fade, institutos e santas casas sem fins lucrativos de 17 munic\u00edpios. Essas entidades auxiliam o trabalho do Sistema \u00danico de Sa\u00fade e receberam um repasse, em \u00e2mbito nacional, de R$ 2 bilh\u00f5es.<\/p>\n\n\n\n<p>Dentro de um investimento nacional de R$ 600 milh\u00f5es, Mato Grosso recebeu R$ 10 milh\u00f5es para assegurar a realiza\u00e7\u00e3o de cirurgias eletivas, aqueles procedimentos programados e que n\u00e3o s\u00e3o considerados de urg\u00eancia, nos quais o m\u00e9dico agenda o dia e o hor\u00e1rio conforme mapa cir\u00fargico do hospital.<\/p>\n\n\n\n<p>Outra frente de a\u00e7\u00e3o na sa\u00fade nestes 100 primeiros dias de atua\u00e7\u00e3o do Governo Federal foi a retomada do programa Mais M\u00e9dicos, que garantiu 95 vagas para o Mato Grosso, para atua\u00e7\u00e3o em 51 munic\u00edpios. O programa tamb\u00e9m reservou 32 vagas para m\u00e9dicos trabalharem em terras ind\u00edgenas do estado.<\/p>\n\n\n\n<p><strong>MERENDA &#8211; <\/strong>Mato Grosso foi o segundo estado do Centro-Oeste com maior reajuste no valor do Programa Nacional de Alimenta\u00e7\u00e3o Escolar (PNAE). O or\u00e7amento para Mato Grosso foi ampliado em 38,3% em rela\u00e7\u00e3o ao total pago pelo programa no ano passado. Com isso, o estado contar\u00e1 com R$ 101,2 milh\u00f5es em recursos para investir na melhoria da qualidade da merenda servida nas escolas de todos seus munic\u00edpios. Em \u00e2mbito nacional, o PNAE teve reajuste m\u00e9dio de 36% e o investimento saltou de R$ 4 bilh\u00f5es para R$ 5,5 bilh\u00f5es, com impacto na alimenta\u00e7\u00e3o de 40 milh\u00f5es de estudantes.<\/p>\n\n\n\n<p><strong>MINHA CASA, MINHA VIDA &#8211; <\/strong>Na \u00e1rea da habita\u00e7\u00e3o, Mato Grosso foi um dos estados do pa\u00eds contemplados na retomada da entrega de unidades habitacionais do Minha Casa, Minha Vida. Na cidade de Rondon\u00f3polis, 1.152 unidades foram entregues no Residencial Celina Bezerra. A inten\u00e7\u00e3o do Governo Federal \u00e9 garantir a contrata\u00e7\u00e3o de 2 milh\u00f5es de unidades at\u00e9 o fim de 2026.<\/p>\n\n\n\n<p><strong>O BRASIL VOLTOU &#8211; <\/strong>No plano nacional, os primeiros cem dias foram marcados pela retomada de programas essenciais para que o pa\u00eds se coloque na condi\u00e7\u00e3o de combater a fome e a mis\u00e9ria e de gerar oportunidades de emprego, renda e cidadania. O Bolsa Fam\u00edlia, em mar\u00e7o, chegou a 21,1 milh\u00f5es de fam\u00edlias contempladas, com repasse m\u00e9dio recorde de R$ 670,33 e o investimento in\u00e9dito de R$ 14 bilh\u00f5es.<\/p>\n\n\n\n<p>Os sal\u00e1rios dos professores da educa\u00e7\u00e3o b\u00e1sica foram reajustados em quase 15%. Bolsas de estudo, pesquisa e forma\u00e7\u00e3o acad\u00eamica, incluindo gradua\u00e7\u00e3o, p\u00f3s-gradua\u00e7\u00e3o, inicia\u00e7\u00e3o cient\u00edfica e de perman\u00eancia foram reajustadas em at\u00e9 200%.<\/p>\n\n\n\n<p>Na sa\u00fade, o Programa Nacional de Redu\u00e7\u00e3o das Filas de Cirurgias Eletivas tem R$ 600 milh\u00f5es destinados a estados e munic\u00edpios. O Movimento Nacional pela Vacina\u00e7\u00e3o foi retomado e o Mais M\u00e9dicos para o Brasil abriu 15 mil vagas.<\/p>\n\n\n\n<p>O Minha Casa, Minha Vida resgatou a Faixa 1 do programa, voltada para moradias subsidiadas. A meta \u00e9 contratar 2 milh\u00f5es de moradias at\u00e9 2026. Ainda na infraestrutura, o Governo Federal retomou o pacto federativo e passou a equacionar com estados e munic\u00edpios as prioridades em torno de 14 mil obras que estavam paralisadas em todas as 27 Unidades da Federa\u00e7\u00e3o.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es ainda envolveram o avan\u00e7o em pol\u00edticas de igualdade de g\u00eanero, com destaque para o Projeto de Lei 1085\/23, que determina a mesma remunera\u00e7\u00e3o para homens e mulheres que exer\u00e7am a mesma fun\u00e7\u00e3o. O pa\u00eds se mobilizou em a\u00e7\u00f5es de combate ao racismo, com o Governo Federal dando o exemplo e anunciando que 30% dos cargos de confian\u00e7a ser\u00e3o ocupados por pessoas negras.<\/p>\n\n\n\n<p>O meio ambiente voltou a ser tratado com seriedade e o Fundo Amaz\u00f4nia, gerido pelo BNDES, passou a receber investimentos estrangeiros. Na seguran\u00e7a, foi relan\u00e7ado o Pronasci, destinado \u00e0 preven\u00e7\u00e3o, controle e repress\u00e3o da criminalidade com foco na promo\u00e7\u00e3o da cidadania e no enfrentamento ao feminic\u00eddio. No plano internacional, houve o resgate do prest\u00edgio nas rela\u00e7\u00f5es internacionais e do protagonismo brasileiro.<\/p>\n\n\n\n<p>Da Assessoria<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estado tem maior valor m\u00e9dio do Bolsa Fam\u00edlia no Centro-Oeste, reajuste de 38% na merenda<\/p>\n","protected":false},"author":2,"featured_media":118776,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-118775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=118775"}],"version-history":[{"count":2,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118775\/revisions"}],"predecessor-version":[{"id":118782,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118775\/revisions\/118782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/118776"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=118775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=118775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=118775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}