{"id":118651,"date":"2023-04-09T18:08:24","date_gmt":"2023-04-09T21:08:24","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/09\/cara-de-sapato-confirma-retorno-as-lutas-e-define-addversario-ideal\/"},"modified":"2023-04-09T18:08:24","modified_gmt":"2023-04-09T21:08:24","slug":"cara-de-sapato-confirma-retorno-as-lutas-e-define-addversario-ideal","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/09\/cara-de-sapato-confirma-retorno-as-lutas-e-define-addversario-ideal\/","title":{"rendered":"Cara de Sapato confirma retorno \u00e0s lutas e define addvers\u00e1rio ideal"},"content":{"rendered":"<p>Ap\u00f3s participar do BBB 23, Cara de Sapato j\u00e1 sabe quando vai voltar a lutar profissionalmente. Em entrevista para o Combate, o lutador garantiu que pretende voltar ao oct\u00f3gono ainda em 2023 e tem o Youtuber Jake Paul como advers\u00e1rio preferido para este retorno.<\/p>\n<p>&#8220;Acho que seria \u00f3timo enfrentar o Jake Paul. Ele ainda n\u00e3o fez nenhuma luta de MMA e eu como campe\u00e3o de 2021 seria excelente. N\u00e3o sei se ele est\u00e1 \u00e0 disposi\u00e7\u00e3o, mas seria espetacular. Adoraria lutar com ele&#8221;, disse Cara de Sapato.<\/p>\n<\/p>\n<p>Apesar de j\u00e1 ter um advers\u00e1rio definido, vai levar algum tempo para que Cara de Sapato volte a lutar. Durante sua participa\u00e7\u00e3o no BBB, o lutador falou algumas vezes que precisava se recuperar de uma cirurgia muito s\u00e9ria no joelho antes de retornar ao ritmo de combate. Por conta disso, o brasileiro sabe que a volta vai levar alguns bons meses.<\/p>\n<\/p>\n<p>&#8220;A cirurgia foi bem agressiva. Eu lesionei o menisco, ligamentos, ent\u00e3o eu preciso me dedicar bastante para chegar a 100%. Eu n\u00e3o quero fazer nada meia boca. Lutar a temporada regular n\u00e3o \u00e9 uma op\u00e7\u00e3o. A recupera\u00e7\u00e3o est\u00e1 triste. Eu j\u00e1 tinha passado por uma cirurgia no joelho, ent\u00e3o j\u00e1 n\u00e3o vinha conseguindo treinar forte. Agora est\u00e1 sendo muito bom. Suar de novo, sentir a energia da galera est\u00e1 sendo massa para me preparar para mesmo lutar o quanto antes. Estou morrendo de saudade de lutar&#8221;, disse Cara de Sapato.<\/p>\n<\/p>\n<p>&#8220;Ainda n\u00e3o tem nada certo. Eu falei com meu empres\u00e1rio e ele j\u00e1 disse que eu vou estar apto a lutar mais ou menos no final do ano. De repente em um dos dois \u00faltimos eventos ali do PFL, que ainda n\u00e3o sei quando \u00e9 exatamente. Agora \u00e9 s\u00f3 ver quest\u00e3o de acordo da luta que t\u00e1 na m\u00e3o do empres\u00e1rio&#8221;, explicou o lutador.<\/p>\n<\/p>\n<p>BBB 23<\/p>\n<p>Cara de Sapato foi expulso da atual edi\u00e7\u00e3o do BBB23 no dia 16 de mar\u00e7o, na quinta-feira, antes da prova do l\u00edder daquela semana. Al\u00e9m dele, MC Guim\u00ea tamb\u00e9m foi eliminado, ambos foram acusados de ass\u00e9dio e importuna\u00e7\u00e3o sexual pelas investidas na mexicana Dania Mendez, participante da La Casa de Los Famosos convidada para fazer interc\u00e2mbio com o programa brasileiro. Key Alves foi a escolhida do BBB23 para conhecer a vers\u00e3o mexicana do reality show.<\/p>\n<\/p>\n<p>Na festa do l\u00edder de MC Guim\u00ea, no dia anterior \u00e0 expuls\u00e3o, Cara de Sapato tentou, algumas vezes, beijar Dania Mendez. Nas redes sociais, usu\u00e1rios apontaram que a modelo n\u00e3o estava \u00e0 vontade quando o lutador a beijou e tentou se desvencilhar. Ap\u00f3s a sa\u00edda de MC Guim\u00ea e Cara de Sapato, ambos foram intimados a prestar depoimento na Delegacia da Mulher de Jacarepagu\u00e1, no Rio de Janeiro. O cantor prestou depoimento em 20 de mar\u00e7o, enquanto o atleta dep\u00f4s no dia 22.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2007658\/cara-de-sapato-confirma-retorno-as-lutas-e-define-addversario-ideal?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s participar do BBB 23, Cara de Sapato j\u00e1 sabe quando vai voltar a lutar<\/p>\n","protected":false},"author":0,"featured_media":118652,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-118651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=118651"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/118652"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=118651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=118651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=118651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}