{"id":118643,"date":"2023-04-09T16:08:31","date_gmt":"2023-04-09T19:08:31","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/09\/messi-faz-gol-e-da-assistencia-um-jogo-apos-ser-vaiado-e-psg-vence-o-nice\/"},"modified":"2023-04-09T16:08:31","modified_gmt":"2023-04-09T19:08:31","slug":"messi-faz-gol-e-da-assistencia-um-jogo-apos-ser-vaiado-e-psg-vence-o-nice","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/09\/messi-faz-gol-e-da-assistencia-um-jogo-apos-ser-vaiado-e-psg-vence-o-nice\/","title":{"rendered":"Messi faz gol e d\u00e1 assist\u00eancia um jogo ap\u00f3s ser vaiado, e PSG vence o Nice"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL-FOLHAPRESS) &#8211; Messi respondeu dentro de campo neste s\u00e1bado (8) as vaias que ouviu da torcida do PSG no \u00faltimo jogo da equipe.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Ele marcou um gol e deu uma assist\u00eancia na vit\u00f3ria do PSG sobre o Nice, por 2 a 0, pelo Campeonato Franc\u00eas.<br \/>O outro gol do time da capital francesa foi anotado por Sergio Ramos.<\/p>\n<p>O argentino chegou a 19 gols e 18 assist\u00eancias na atual temporada.<\/p>\n<p>Fora de campo, Messi tem situa\u00e7\u00e3o indefinida dentro do PSG. Seu contrato vai at\u00e9 o final da atual temporada e a imprensa europeia especula um retorno ao Barcelona.<br \/>A vit\u00f3ria alivia a press\u00e3o no PSG, que havia perdido seus \u00faltimos dois jogos para Rennes e Lyon.<br \/>POR QUE MESSI FOI VAIADO?<br \/>As vaias a Messi come\u00e7aram na partida contra o Rennes, em 19 de mar\u00e7o. A partida foi a primeira ap\u00f3s a elimina\u00e7\u00e3o do PSG para o Bayern de Munique na Champions League.<br \/>No jogo seguinte, contra o Lyon, o argentino foi novamente vaiado pela torcida do PSG.<br \/>Em ambas as partidas, as vaias aconteceram quando o nome e a foto do jogador apareceram na divulga\u00e7\u00e3o da escala\u00e7\u00e3o da equipe.<br \/>A imprensa francesa afirma que as vaias a Messi, al\u00e9m do rendimento em campo, tamb\u00e9m se devem pela indefini\u00e7\u00e3o da sua perman\u00eancia no clube.NICE<br \/>Schmeichel; Dante, Todibo e Ndayishimiye; Mendy (Ros\u00e1rio), Thuram, Boudaoui (Laborde) e Bard (Brahimi); Ramsey; P\u00e9p\u00e9 e Moffi (Bouanani). T.: Didier DigardPSG<br \/>Donnarumma; Sergio Ramos, Marquinhos e Danilo Pereira; Hakimi, Renato Sanches (Fabi\u00e1n Ruiz), Vitinha, Carlos Soler (Zaire-Emery) e Nuno Mendes (Bitshiabu); Messi e Mbapp\u00e9. T.: Christophe GaltierLocal: Allianz Riviera, em Nice, na Fran\u00e7a<br \/>\u00c1rbitro: J\u00e9r\u00e9mie Pignard<br \/>Cart\u00e3o amarelo: Thuram (NIC)<br \/>Gols: Messi (25&#8217;\/1\u00b0), Sergio Ramos (30&#8217;\/2\u00b0T)<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2007665\/messi-faz-gol-e-da-assistencia-um-jogo-apos-ser-vaiado-e-psg-vence-o-nice?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL-FOLHAPRESS) &#8211; Messi respondeu dentro de campo neste s\u00e1bado (8) as vaias<\/p>\n","protected":false},"author":0,"featured_media":118644,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-118643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=118643"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/118644"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=118643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=118643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=118643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}