{"id":118415,"date":"2023-04-07T21:08:30","date_gmt":"2023-04-08T00:08:30","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/07\/mansao-de-michael-jordan-e-invadida-e-suspeito-e-preso-no-local\/"},"modified":"2023-04-07T21:08:30","modified_gmt":"2023-04-08T00:08:30","slug":"mansao-de-michael-jordan-e-invadida-e-suspeito-e-preso-no-local","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/07\/mansao-de-michael-jordan-e-invadida-e-suspeito-e-preso-no-local\/","title":{"rendered":"Mans\u00e3o de Michael Jordan \u00e9 invadida, e suspeito \u00e9 preso no local"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; A casa de Michael Jordan teria sido invadida, na ter\u00e7a-feira (4), e um homem foi preso no local.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A pol\u00edcia foi alertada sobre um roubo na mans\u00e3o da lenda da NBA. A informa\u00e7\u00e3o \u00e9 da revista americana People.<\/p>\n<p>A propriedade tem 28 mil m\u00b2 e fica localizada em Highland Park, Illinois (EUA).<\/p>\n<p>As autoridades n\u00e3o suspeitam que o homem quisesse levar algo da casa, pois apenas uma janela foi danificada.<\/p>\n<p>O homem foi acusado de tr\u00eas contraven\u00e7\u00f5es: uma por invas\u00e3o criminosa de resid\u00eancia ocupada e duas por danos criminais \u00e0 propriedade.<\/p>\n<p>Ele foi libertado sob fian\u00e7a. Uma audi\u00eancia est\u00e1 marcada no tribunal para 20 de abril.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2007380\/mansao-de-michael-jordan-e-invadida-e-suspeito-e-preso-no-local?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; A casa de Michael Jordan teria sido invadida, na ter\u00e7a-feira<\/p>\n","protected":false},"author":0,"featured_media":118416,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-118415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=118415"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/118415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/118416"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=118415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=118415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=118415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}