{"id":1060,"date":"2021-03-22T19:23:16","date_gmt":"2021-03-22T22:23:16","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/22\/gremio-e-eleito-o-melhor-time-sul-americano-da-decada-por-entidade-internacional\/"},"modified":"2021-03-22T19:23:16","modified_gmt":"2021-03-22T22:23:16","slug":"gremio-e-eleito-o-melhor-time-sul-americano-da-decada-por-entidade-internacional","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/22\/gremio-e-eleito-o-melhor-time-sul-americano-da-decada-por-entidade-internacional\/","title":{"rendered":"Gr\u00eamio \u00e9 eleito o melhor time sul-americano da d\u00e9cada por entidade internacional"},"content":{"rendered":"<p>O Gr\u00eamio foi eleito o melhor time sul-americano da d\u00e9cada pela Federa\u00e7\u00e3o Internacional de Hist\u00f3ria e Estat\u00edsticas de Futebol (IFFHS). O clube ga\u00facho lidera o ranking, elaborado a partir da soma dos torneios internacionais e nacionais dentro do continente, com 1.895 pontos. Completam o p\u00f3dio o Atl\u00e9tico Nacional, da Col\u00f4mbia, com 1.853, e o River Plate, 1.749. A Copa Libertadores \u00e9 a competi\u00e7\u00e3o que mais pesa na balan\u00e7a.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O Palmeiras, que \u00e9 o atual campe\u00e3o da Am\u00e9rica do Sul, aparece na d\u00e9cima coloca\u00e7\u00e3o, com 1.536 pontos. Apesar da conquista de t\u00edtulos recentes na d\u00e9cada &#8211; venceu tr\u00eas vezes a Copa do Brasil (2012, 2015 e 2020) e duas vezes o Brasileir\u00e3o (2016 e 2018) &#8211; o time alviverde aparece atr\u00e1s de quatro times brasileiros, Gr\u00eamio, Flamengo, Corinthians e Atl\u00e9tico-MG.<\/p>\n<p>Depois do Gr\u00eamio, o Flamengo \u00e9 o melhor colocado. A equipe da G\u00e1vea, campe\u00e3 da Copa do Brasil (2013), do Brasileir\u00e3o (2019 e 2020), da Copa Libertadores (2019) e da Recopa Sul-Americana (2020), aparece em 6.\u00aa lugar, com 1.590 pontos.<\/p>\n<p>Antes do clube carioca, aparecem Boca Juniors, na quarta coloca\u00e7\u00e3o, com 1.708,5, e o Libertad, do Paraguai, com 1.696,5 pontos, em quinto. Corinthians, com 1.577, Santa Fe, da Col\u00f4mbia, com 1.575 e Atl\u00e9tico-MG, com 1.539, e Palmeiras fecham as dez primeiros lugares da lista.<\/p>\n<p><strong>Confira o ranking dos 10 melhores times sul-americanos da d\u00e9cada do IFFHS:<\/strong><\/p>\n<p>Gr\u00eamio: 1.895<\/p>\n<p>Atl\u00e9tico Nacional-COL: 1.853<\/p>\n<p>River Plate-ARG: 1.749<\/p>\n<p>Boca Juniors-ARG: 1.708,5<\/p>\n<p>Libertad-PAR: 1.696,5<\/p>\n<p>Flamengo: 1.590<\/p>\n<p>Corinthians: 1.577<\/p>\n<p>Santa Fe-COL: 1.575<\/p>\n<p>Atl\u00e9tico-MG: 1.539<\/p>\n<p>Palmeiras: 1.536<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1788510\/gremio-e-eleito-o-melhor-time-sul-americano-da-decada-por-entidade-internacional?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Gr\u00eamio foi eleito o melhor time sul-americano da d\u00e9cada pela Federa\u00e7\u00e3o Internacional de Hist\u00f3ria<\/p>\n","protected":false},"author":0,"featured_media":1061,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1060"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/1061"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}